{"id":1384,"date":"2023-04-21T17:46:23","date_gmt":"2023-04-21T15:46:23","guid":{"rendered":"https:\/\/www.metalworld.it\/nevio\/news\/"},"modified":"2023-05-11T16:34:23","modified_gmt":"2023-05-11T14:34:23","slug":"news","status":"publish","type":"page","link":"https:\/\/www.metalworld.it\/en\/news\/","title":{"rendered":"News"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"tpl-page-raw-code-interne.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-1384","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News | Metal World<\/title>\n<meta name=\"description\" content=\"Un filo diretto con le nostre novit\u00e0. Contenuti costantemente aggiornati riguardanti le novit\u00e0 su di noi, sui nostri prodotti e sui nostri servizi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.metalworld.it\/en\/news\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News | Metal World\" \/>\n<meta property=\"og:description\" content=\"Un filo diretto con le nostre novit\u00e0. Contenuti costantemente aggiornati riguardanti le novit\u00e0 su di noi, sui nostri prodotti e sui nostri servizi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.metalworld.it\/en\/news\/\" \/>\n<meta property=\"og:site_name\" content=\"Metal World\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/METAL-WORLD-SPA\/100054358818321\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-11T14:34:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.metalworld.it\\\/en\\\/news\\\/\",\"url\":\"https:\\\/\\\/www.metalworld.it\\\/en\\\/news\\\/\",\"name\":\"News | Metal World\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.metalworld.it\\\/en\\\/#website\"},\"datePublished\":\"2023-04-21T15:46:23+00:00\",\"dateModified\":\"2023-05-11T14:34:23+00:00\",\"description\":\"Un filo diretto con le nostre novit\u00e0. Contenuti costantemente aggiornati riguardanti le novit\u00e0 su di noi, sui nostri prodotti e sui nostri servizi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.metalworld.it\\\/en\\\/news\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.metalworld.it\\\/en\\\/news\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.metalworld.it\\\/en\\\/news\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.metalworld.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.metalworld.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.metalworld.it\\\/en\\\/\",\"name\":\"Metal World\",\"description\":\"Professional tools all over the world\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.metalworld.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.metalworld.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.metalworld.it\\\/en\\\/#organization\",\"name\":\"Metal World\",\"url\":\"https:\\\/\\\/www.metalworld.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.metalworld.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.metalworld.it\\\/nevio\\\/wp-content\\\/uploads\\\/metal-world-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.metalworld.it\\\/nevio\\\/wp-content\\\/uploads\\\/metal-world-logo.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Metal World\"},\"image\":{\"@id\":\"https:\\\/\\\/www.metalworld.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/METAL-WORLD-SPA\\\/100054358818321\\\/\",\"https:\\\/\\\/it.linkedin.com\\\/company\\\/metal-world-s-p-a\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"News | Metal World","description":"Un filo diretto con le nostre novit\u00e0. Contenuti costantemente aggiornati riguardanti le novit\u00e0 su di noi, sui nostri prodotti e sui nostri servizi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.metalworld.it\/en\/news\/","og_locale":"en_US","og_type":"article","og_title":"News | Metal World","og_description":"Un filo diretto con le nostre novit\u00e0. Contenuti costantemente aggiornati riguardanti le novit\u00e0 su di noi, sui nostri prodotti e sui nostri servizi","og_url":"https:\/\/www.metalworld.it\/en\/news\/","og_site_name":"Metal World","article_publisher":"https:\/\/www.facebook.com\/people\/METAL-WORLD-SPA\/100054358818321\/","article_modified_time":"2023-05-11T14:34:23+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.metalworld.it\/en\/news\/","url":"https:\/\/www.metalworld.it\/en\/news\/","name":"News | Metal World","isPartOf":{"@id":"https:\/\/www.metalworld.it\/en\/#website"},"datePublished":"2023-04-21T15:46:23+00:00","dateModified":"2023-05-11T14:34:23+00:00","description":"Un filo diretto con le nostre novit\u00e0. Contenuti costantemente aggiornati riguardanti le novit\u00e0 su di noi, sui nostri prodotti e sui nostri servizi","breadcrumb":{"@id":"https:\/\/www.metalworld.it\/en\/news\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.metalworld.it\/en\/news\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.metalworld.it\/en\/news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.metalworld.it\/en\/"},{"@type":"ListItem","position":2,"name":"News"}]},{"@type":"WebSite","@id":"https:\/\/www.metalworld.it\/en\/#website","url":"https:\/\/www.metalworld.it\/en\/","name":"Metal World","description":"Professional tools all over the world","publisher":{"@id":"https:\/\/www.metalworld.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.metalworld.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.metalworld.it\/en\/#organization","name":"Metal World","url":"https:\/\/www.metalworld.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.metalworld.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.metalworld.it\/nevio\/wp-content\/uploads\/metal-world-logo.svg","contentUrl":"https:\/\/www.metalworld.it\/nevio\/wp-content\/uploads\/metal-world-logo.svg","width":"1024","height":"1024","caption":"Metal World"},"image":{"@id":"https:\/\/www.metalworld.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/METAL-WORLD-SPA\/100054358818321\/","https:\/\/it.linkedin.com\/company\/metal-world-s-p-a"]}]}},"_links":{"self":[{"href":"https:\/\/www.metalworld.it\/en\/wp-json\/wp\/v2\/pages\/1384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.metalworld.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.metalworld.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.metalworld.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.metalworld.it\/en\/wp-json\/wp\/v2\/comments?post=1384"}],"version-history":[{"count":1,"href":"https:\/\/www.metalworld.it\/en\/wp-json\/wp\/v2\/pages\/1384\/revisions"}],"predecessor-version":[{"id":1409,"href":"https:\/\/www.metalworld.it\/en\/wp-json\/wp\/v2\/pages\/1384\/revisions\/1409"}],"wp:attachment":[{"href":"https:\/\/www.metalworld.it\/en\/wp-json\/wp\/v2\/media?parent=1384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}